{"id":46920,"date":"2022-08-28T00:00:00","date_gmt":"2022-08-27T16:00:00","guid":{"rendered":"https:\/\/www.hkmu.edu.hk\/lemon101prototype\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/"},"modified":"2022-08-28T00:00:00","modified_gmt":"2022-08-27T16:00:00","slug":"%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b","status":"publish","type":"post","link":"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/","title":{"rendered":"\u8cb7\u6a13\u7a0b\u5e8f2022\uff5c\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6\uff1f\u7747\u6a13\u7d19\uff0b\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04\uff0b\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04\uff0b\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\u4e8b\u9805\u4e00\u89bd (in Chinese)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.businesstimes.com.hk\/articles\/140823\/\u8cb7\u6a13\u7a0b\u5e8f2022-\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6-\u7747\u6a13\u7d19-\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04-\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04-\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\/<\/p>\n","protected":false},"author":320,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"categories":[108,112],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v17.3 (Yoast SEO v21.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u8cb7\u6a13\u7a0b\u5e8f2022\uff5c\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6\uff1f\u7747\u6a13\u7d19\uff0b\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04\uff0b\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04\uff0b\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\u4e8b\u9805\u4e00\u89bd (in Chinese) - News Centre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u8cb7\u6a13\u7a0b\u5e8f2022\uff5c\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6\uff1f\u7747\u6a13\u7d19\uff0b\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04\uff0b\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04\uff0b\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\u4e8b\u9805\u4e00\u89bd (in Chinese)\" \/>\n<meta property=\"og:description\" content=\"https:\/\/www.businesstimes.com.hk\/articles\/140823\/\u8cb7\u6a13\u7a0b\u5e8f2022-\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6-\u7747\u6a13\u7d19-\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04-\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04-\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\/\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/\" \/>\n<meta property=\"og:site_name\" content=\"News Centre\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-27T16:00:00+00:00\" \/>\n<meta name=\"author\" content=\"lemon101\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"lemon101\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u8cb7\u6a13\u7a0b\u5e8f2022\uff5c\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6\uff1f\u7747\u6a13\u7d19\uff0b\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04\uff0b\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04\uff0b\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\u4e8b\u9805\u4e00\u89bd (in Chinese) - News Centre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/","og_locale":"en_US","og_type":"article","og_title":"\u8cb7\u6a13\u7a0b\u5e8f2022\uff5c\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6\uff1f\u7747\u6a13\u7d19\uff0b\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04\uff0b\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04\uff0b\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\u4e8b\u9805\u4e00\u89bd (in Chinese)","og_description":"https:\/\/www.businesstimes.com.hk\/articles\/140823\/\u8cb7\u6a13\u7a0b\u5e8f2022-\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6-\u7747\u6a13\u7d19-\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04-\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04-\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\/","og_url":"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/","og_site_name":"News Centre","article_published_time":"2022-08-27T16:00:00+00:00","author":"lemon101","twitter_card":"summary_large_image","twitter_misc":{"Written by":"lemon101"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/","url":"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/","name":"\u8cb7\u6a13\u7a0b\u5e8f2022\uff5c\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6\uff1f\u7747\u6a13\u7d19\uff0b\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04\uff0b\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04\uff0b\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\u4e8b\u9805\u4e00\u89bd (in Chinese) - News Centre","isPartOf":{"@id":"https:\/\/www.hkmu.edu.hk\/news\/#website"},"datePublished":"2022-08-27T16:00:00+00:00","dateModified":"2022-08-27T16:00:00+00:00","author":{"@id":"https:\/\/www.hkmu.edu.hk\/news\/#\/schema\/person\/40afcddf5fb509d962797d7a75edadac"},"breadcrumb":{"@id":"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hkmu.edu.hk\/news\/%e8%b2%b7%e6%a8%93%e7%a8%8b%e5%ba%8f2022%ef%bd%9c%e8%b2%b7%e4%b8%80%e6%89%8b%e6%a8%93%e8%a6%81%e7%b0%bd%e5%b9%be%e5%a4%9a%e4%bb%bd%e6%96%87%e4%bb%b6%ef%bc%9f%e7%9d%87%e6%a8%93%e7%b4%99%ef%bc%8b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"News","item":"\/news\/"},{"@type":"ListItem","position":2,"name":"\u8cb7\u6a13\u7a0b\u5e8f2022\uff5c\u8cb7\u4e00\u624b\u6a13\u8981\u7c3d\u5e7e\u591a\u4efd\u6587\u4ef6\uff1f\u7747\u6a13\u7d19\uff0b\u81e8\u6642\u8cb7\u8ce3\u5408\u7d04\uff0b\u6b63\u5f0f\u8cb7\u8ce3\u5408\u7d04\uff0b\u6309\u63ed\u6587\u4ef6\u6ce8\u610f\u4e8b\u9805\u4e00\u89bd (in Chinese)"}]},{"@type":"WebSite","@id":"https:\/\/www.hkmu.edu.hk\/news\/#website","url":"https:\/\/www.hkmu.edu.hk\/news\/","name":"News Centre","description":"News Centre - Hong Kong Metropolitan University","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hkmu.edu.hk\/news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.hkmu.edu.hk\/news\/#\/schema\/person\/40afcddf5fb509d962797d7a75edadac","name":"lemon101","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hkmu.edu.hk\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/33be895f05868d08ce0142a2f686b9d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33be895f05868d08ce0142a2f686b9d0?s=96&d=mm&r=g","caption":"lemon101"},"url":"https:\/\/www.hkmu.edu.hk\/news\/author\/lemon101\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/posts\/46920"}],"collection":[{"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/users\/320"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/comments?post=46920"}],"version-history":[{"count":0,"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/posts\/46920\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/media?parent=46920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/categories?post=46920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hkmu.edu.hk\/news\/wp-json\/wp\/v2\/tags?post=46920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}