{"id":55511,"date":"2025-12-18T20:04:14","date_gmt":"2025-12-18T12:04:14","guid":{"rendered":"https:\/\/www.hkmu.edu.hk\/as\/research\/ihcorc\/20260309-singing-style-concert\/"},"modified":"2025-12-22T17:19:48","modified_gmt":"2025-12-22T09:19:48","slug":"20260309-singing-style-concert","status":"publish","type":"page","link":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/","title":{"rendered":"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"55511\" class=\"elementor elementor-55511 elementor-55499\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"has_eae_slider wavo-column-gap-default elementor-section elementor-top-section elementor-element elementor-element-1abad90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1abad90\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd2e172\" data-id=\"bd2e172\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dfbfc4 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"5dfbfc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider wavo-column-gap-default elementor-section elementor-top-section elementor-element elementor-element-97ba699 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97ba699\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3980ae\" data-id=\"b3980ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9871ce9 elementor-widget elementor-widget-text-editor\" data-id=\"9871ce9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>\u300a\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a\u300b\u4e43\u9999\u6e2f\u90fd\u4f1a\u5927\u5b66\u4f55\u9648\u5a49\u73cd\u7ca4\u5267\u7814\u827a\u4e2d\u5fc3\uff08\u4e0b\u79f0\u7814\u827a\u4e2d\u5fc3\uff09\u9686\u91cd\u5448\u732e\u4e4b\u66f2\u827a\u76db\u4e8b\u3002\u6f14\u5531\u4f1a\u65e8\u5728\u4ee5\u8d4f\u6790\u4e0e\u6f14\u7ece\u5e76\u91cd\u4e4b\u5f62\u5f0f\uff0c\u5c55\u793a\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u4e4b\u591a\u6837\u6027\uff0c\u5e76\u4ee5\u5b66\u672f\u5206\u6790\u4e3a\u57fa\u7840\uff0c\u6df1\u5165\u63a2\u8ba8\u5176\u5386\u53f2\u6e0a\u6e90\u4e0e\u827a\u672f\u4ef7\u503c\u3002<\/p><p>\u300a\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a\u300b\u4e3a\u987e\u66f2\u5468\u90ce\u53ca\u6587\u5316\u7814\u7a76\u8005\u63d0\u4f9b\u4e00\u96be\u5f97\u4e4b\u673a\u4f1a\uff0c\u6df1\u5165\u9886\u7565\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u4e4b\u9b45\u529b\u4e0e\u7cbe\u9ad3\u3002\u77e5\u97f3\u8005\u4e07\u52ff\u9519\u8fc7\uff01<\/p><h3 style=\"text-align: center;\"><span style=\"color: #ff0000;\">\u95e8\u7968\u4e8e2026\u5e741\u670819\u65e5 (\u661f\u671f\u4e00) \u4e0a\u534810\u65f6\u8d77\u516c\u5f00\u53d1\u552e<\/span><\/h3>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider wavo-column-gap-default elementor-section elementor-top-section elementor-element elementor-element-e5e24f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5e24f0\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-700588a\" data-id=\"700588a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72bc7df elementor-widget elementor-widget-image\" data-id=\"72bc7df\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"768\" height=\"1077\" src=\"https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-768x1077.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-768x1077.jpg 768w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-214x300.jpg 214w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-730x1024.jpg 730w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-1095x1536.jpg 1095w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-1460x2048.jpg 1460w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-scaled.jpg 1825w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider wavo-column-gap-default elementor-section elementor-top-section elementor-element elementor-element-94e1281 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94e1281\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b8894c\" data-id=\"2b8894c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-534129e elementor-widget elementor-widget-image\" data-id=\"534129e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"768\" height=\"1077\" src=\"https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet-back_rgb_compressed-768x1077.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet-back_rgb_compressed-768x1077.jpg 768w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet-back_rgb_compressed-214x300.jpg 214w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet-back_rgb_compressed-730x1024.jpg 730w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet-back_rgb_compressed-1095x1536.jpg 1095w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet-back_rgb_compressed-1460x2048.jpg 1460w, https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet-back_rgb_compressed-scaled.jpg 1825w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a \u300a\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a\u300b\u4e43\u9999\u6e2f\u90fd\u4f1a\u5927\u5b66\u4f55\u9648\u5a49\u73cd\u7ca4\u5267\u7814\u827a\u4e2d\u5fc3\uff08\u4e0b\u79f0\u7814\u827a\u4e2d\u5fc3\uff09\u9686\u91cd\u5448\u732e\u4e4b\u66f2\u827a\u76db\u4e8b\u3002\u6f14\u5531\u4f1a\u65e8\u5728\u4ee5\u8d4f\u6790\u4e0e\u6f14\u7ece\u5e76\u91cd\u4e4b\u5f62\u5f0f\uff0c\u5c55\u793a\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u4e4b\u591a\u6837\u6027\uff0c\u5e76\u4ee5\u5b66\u672f\u5206\u6790\u4e3a\u57fa\u7840\uff0c\u6df1\u5165\u63a2\u8ba8\u5176\u5386\u53f2\u6e0a\u6e90\u4e0e\u827a\u672f\u4ef7\u503c\u3002\u300a\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a\u300b\u4e3a\u987e\u66f2\u5468\u90ce\u53ca\u6587\u5316\u7814\u7a76\u8005\u63d0\u4f9b\u4e00\u96be\u5f97\u4e4b\u673a\u4f1a\uff0c\u6df1\u5165\u9886\u7565\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u4e4b\u9b45\u529b\u4e0e\u7cbe\u9ad3\u3002\u77e5\u97f3\u8005\u4e07\u52ff\u9519\u8fc7\uff01\u95e8\u7968\u4e8e2026\u5e741\u670819\u65e5 (\u661f\u671f\u4e00) \u4e0a\u534810\u65f6\u8d77\u516c\u5f00\u53d1\u552e<\/p>\n","protected":false},"author":636,"featured_media":0,"parent":37123,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"content_default_2.php","meta":{"_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v17.3 (Yoast SEO v21.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a - School of Arts and Social Sciences - Hong Kong Metropolitan University<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a\" \/>\n<meta property=\"og:description\" content=\"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/\" \/>\n<meta property=\"og:site_name\" content=\"School of Arts and Social Sciences - Hong Kong Metropolitan University\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T09:19:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-768x1077.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a - School of Arts and Social Sciences - Hong Kong Metropolitan University","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a","og_description":"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a","og_url":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/","og_site_name":"School of Arts and Social Sciences - Hong Kong Metropolitan University","article_modified_time":"2025-12-22T09:19:48+00:00","og_image":[{"url":"https:\/\/www.hkmu.edu.hk\/as\/wp-content\/uploads\/sites\/3\/2025\/12\/leaflet_front_rgb_compressed-768x1077.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/","url":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/","name":"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a - School of Arts and Social Sciences - Hong Kong Metropolitan University","isPartOf":{"@id":"https:\/\/www.hkmu.edu.hk\/as\/#website"},"datePublished":"2025-12-18T12:04:14+00:00","dateModified":"2025-12-22T09:19:48+00:00","breadcrumb":{"@id":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/20260309-singing-style-concert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u4eba\u6587\u793e\u4f1a\u79d1\u5b66\u9662","item":"\/as\/sc\/"},{"@type":"ListItem","position":2,"name":"\u7814\u7a76","item":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/"},{"@type":"ListItem","position":3,"name":"\u4f55\u9648\u5a49\u73cd\u7ca4\u5267\u7814\u827a\u4e2d\u5fc3","item":"https:\/\/www.hkmu.edu.hk\/as\/sc\/research\/ihcorc\/"},{"@type":"ListItem","position":4,"name":"\u7ca4\u5267\u5531\u8154\u6d41\u6d3e\u8d4f\u6790\u6f14\u5531\u4f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.hkmu.edu.hk\/as\/#website","url":"https:\/\/www.hkmu.edu.hk\/as\/","name":"School of Arts and Social Sciences - Hong Kong Metropolitan University","description":"School of Arts and Social Sciences -  Hong Kong Metropolitan University","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hkmu.edu.hk\/as\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"}]}},"_links":{"self":[{"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/pages\/55511"}],"collection":[{"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/users\/636"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/comments?post=55511"}],"version-history":[{"count":13,"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/pages\/55511\/revisions"}],"predecessor-version":[{"id":55658,"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/pages\/55511\/revisions\/55658"}],"up":[{"embeddable":true,"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/pages\/37123"}],"wp:attachment":[{"href":"https:\/\/www.hkmu.edu.hk\/as\/sc\/wp-json\/wp\/v2\/media?parent=55511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}